{"id":3467,"date":"2023-06-25T14:15:05","date_gmt":"2023-06-25T19:15:05","guid":{"rendered":"http:\/\/iesevilla.edu.co\/sitio\/?p=3467"},"modified":"2023-06-28T14:32:57","modified_gmt":"2023-06-28T19:32:57","slug":"talentos-deportivos-liceistas","status":"publish","type":"post","link":"http:\/\/iesevilla.edu.co\/sitio\/talentos-deportivos-liceistas\/","title":{"rendered":"TALENTOS DEPORTIVOS LICEISTAS"},"content":{"rendered":"<p><a href=\"http:\/\/iesevilla.edu.co\/sitio\/wp-content\/uploads\/2023\/06\/Diego-Fernando-Orozco.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3469\" src=\"http:\/\/iesevilla.edu.co\/sitio\/wp-content\/uploads\/2023\/06\/Diego-Fernando-Orozco-499x1024.jpeg\" alt=\"\" width=\"499\" height=\"1024\" srcset=\"http:\/\/iesevilla.edu.co\/sitio\/wp-content\/uploads\/2023\/06\/Diego-Fernando-Orozco-499x1024.jpeg 499w, http:\/\/iesevilla.edu.co\/sitio\/wp-content\/uploads\/2023\/06\/Diego-Fernando-Orozco-146x300.jpeg 146w, http:\/\/iesevilla.edu.co\/sitio\/wp-content\/uploads\/2023\/06\/Diego-Fernando-Orozco.jpeg 624w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><\/a><\/p>\n<p>Nuestro estudiante Diego Fernando Orozco Le\u00f3n del Ciclo 5, jornada nocturna, se acaba de coronar Campe\u00f3n Nacional de Atletismo en la prueba de los 5000 metros planos categor\u00eda U20, en Santa Marta.<\/p>\n<p>En artes marciales, especificamente Jiu-Jitsu, Emanuel Palacio Escobar alumno del grado 10-3, en la\u00a0 categor\u00eda adulto, obtuvo medalla de bronce en el Campeonato de Jiu-jitsu celbrado en Ibagu\u00e9, domingo pasado. As\u00ed mismo la estudiante Mar\u00eda Isabela Morales estudiante del grado 10-3; obtuvo tres medallas de oro en Jiu-jitsu, categor\u00edas 69-74 y absoluto.<\/p>\n<p>Felicitaciones a nuestros estudiantes por poner en alto el nombre de Sevilla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestro estudiante Diego Fernando Orozco Le\u00f3n del Ciclo 5, jornada nocturna, se acaba de coronar Campe\u00f3n Nacional de Atletismo en la prueba de los 5000 metros planos categor\u00eda U20, en Santa Marta. En artes marciales, especificamente Jiu-Jitsu, Emanuel Palacio Escobar alumno del grado 10-3, en&nbsp;<a href=\"http:\/\/iesevilla.edu.co\/sitio\/talentos-deportivos-liceistas\/\">&hellip;<\/a><\/p>\n","protected":false},"author":2,"featured_media":3098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"#ffffff","slide_template_v7":"","footnotes":""},"categories":[124,10],"tags":[],"class_list":["post-3467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estudiantes","category-reconocimiento","odd"],"_links":{"self":[{"href":"http:\/\/iesevilla.edu.co\/sitio\/wp-json\/wp\/v2\/posts\/3467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/iesevilla.edu.co\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iesevilla.edu.co\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iesevilla.edu.co\/sitio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/iesevilla.edu.co\/sitio\/wp-json\/wp\/v2\/comments?post=3467"}],"version-history":[{"count":1,"href":"http:\/\/iesevilla.edu.co\/sitio\/wp-json\/wp\/v2\/posts\/3467\/revisions"}],"predecessor-version":[{"id":3470,"href":"http:\/\/iesevilla.edu.co\/sitio\/wp-json\/wp\/v2\/posts\/3467\/revisions\/3470"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/iesevilla.edu.co\/sitio\/wp-json\/wp\/v2\/media\/3098"}],"wp:attachment":[{"href":"http:\/\/iesevilla.edu.co\/sitio\/wp-json\/wp\/v2\/media?parent=3467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iesevilla.edu.co\/sitio\/wp-json\/wp\/v2\/categories?post=3467"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iesevilla.edu.co\/sitio\/wp-json\/wp\/v2\/tags?post=3467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}